{"id":11466,"date":"2023-02-06T11:46:38","date_gmt":"2023-02-06T10:46:38","guid":{"rendered":"https:\/\/burckhardt.swiss\/sur-le-terrain-le-bim-chez-burckhardt\/"},"modified":"2023-03-14T10:27:09","modified_gmt":"2023-03-14T09:27:09","slug":"sur-le-terrain-le-bim-chez-burckhardt","status":"publish","type":"post","link":"https:\/\/burckhardt.swiss\/fr\/sur-le-terrain-le-bim-chez-burckhardt\/","title":{"rendered":"Sur le terrain: le BIM chez Burckhardt"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-ebc36467 wp-block-group-is-layout-constrained\">\n<p><strong>Le Building Information Modeling, ou BIM, permet une planification en r\u00e9seau et collaborative de la construction. Mais l\u2019int\u00e9gration du logiciel va bien au-del\u00e0 de cette \u00e9tape et s\u2019\u00e9tend \u00e0 l\u2019ensemble du processus de cr\u00e9ation de valeur d\u2019un b\u00e2timent. Pour tirer le meilleur parti du BIM, il faut red\u00e9finir les r\u00f4les actuels dans le processus de planification. L\u2019architecte Filip Coso \u00e9voque son utilisation chez Burckhardt: <\/strong><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>O\u00f9 et comment as-tu appris la m\u00e9thode BIM?<\/strong><\/p>\n\n\n\n<p>Mes d\u00e9buts dans le BIM remontent \u00e0 2015. \u00c0 mes yeux, on n\u2019a jamais fini d\u2019apprendre et je me forme donc en permanence. Je trouve formidable de creuser toujours plus le sujet. Je fais \u00e9galement profiter Burckhardt de l\u2019exp\u00e9rience internationale que j\u2019ai acquise dans ce domaine au fil de projets \u00e0 Milan, \u00e0 Venise et aux Philippines.    <\/p>\n\n\n\n<p><strong>Quel est ton r\u00f4le dans l\u2019\u00e9quipe BIM de Burckhardt?<\/strong><\/p>\n\n\n\n<p>Je me consid\u00e8re avant tout comme un membre de l\u2019\u00e9quipe, parce que nous ne raisonnons pas vraiment en termes de r\u00f4les hi\u00e9rarchiques. Nous lan\u00e7ons plut\u00f4t ensemble des id\u00e9es et cherchons \u00e0 aller de l\u2019avant. C\u2019est pourquoi nous assumons souvent des t\u00e2ches diff\u00e9rentes, en fonction de la constellation sp\u00e9cifique du projet. Mais je me concentre bien s\u00fbr sur le num\u00e9rique, c\u2019est ma sp\u00e9cialit\u00e9.    <\/p>\n\n\n\n<p><strong><strong>Quels sont les avantages et l\u2019utilit\u00e9 des m\u00e9thodes num\u00e9riques?<\/strong><\/strong><\/p>\n\n\n\n<p>\u00c0 mon sens, le BIM rend le processus de planification et de construction tr\u00e8s transparent. Il facilite la coop\u00e9ration et l\u2019int\u00e9gration tout en \u00e9tant source de coh\u00e9rence et de structure. Tous ces aspects peuvent am\u00e9liorer le processus cr\u00e9atif. Sans compter qu\u2019ils sont tr\u00e8s agr\u00e9ables! N\u00e9anmoins, les avantages ne deviennent visibles qu\u2019une fois la m\u00e9thode correctement utilis\u00e9e. Dans l\u2019intervalle, une forte volont\u00e9 d\u2019apprendre et parfois une certaine tol\u00e9rance \u00e0 la frustration sont n\u00e9cessaires, comme avec toute innovation technique.      <\/p>\n\n\n\n<p><strong><strong><strong><strong>Qu\u2019est-ce que tu attends du BIM \u00e0 l\u2019avenir?<\/strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<p>J\u2019ai dans l\u2019id\u00e9e qu\u2019il reste un certain nombre de points \u00e0 r\u00e9gler au niveau des processus num\u00e9riques dans l\u2019industrie de la construction. Des am\u00e9liorations en termes de flexibilit\u00e9, d\u2019int\u00e9gration et de transparence des donn\u00e9es sont n\u00e9cessaires. Ceci dit, ma principale attente n\u2019a rien \u00e0 voir avec la technologie, mais avec l\u2019\u00eatre humain: mieux nous comprendrons les processus num\u00e9riques dans la construction, plus notre contribution professionnelle sera pr\u00e9cieuse. Nous y gagnerons et notre travail aussi.   <\/p>\n\n\n<div\n  id=\"block_ab2f948204ccde358a46e35b89155fbe\"\n  data-block_ab2f948204ccde358a46e35b89155fbe\n  class=\"o-flex o-flex--centered back align\"\n>\n  <a href=\"https:\/\/burckhardt.swiss\/fr\/?page_id=249\" class=\"u-arrow--left\" onclick=\"back(event)\">\n    retour\n  <\/a>\n<\/div>\n\n<\/div>\n\n\n<div\n  id=\"block_567e9f0fc4db0c779929a7e91329261a\"\n  data-block_567e9f0fc4db0c779929a7e91329261a\n  class=\"o-flex o-flex--wrap c-block-contacts contacts align\"\n>\n            <div class=\"o-flex__item u-1\/2@tablet c-block-contacts__text\">\n        <div>\n          <h3>Contactez nous!<\/h3>\n          <a\n            role=\"button\"\n            href=\"mailto:stephanie.koehler@burckhardt.swiss\"\n          >\n            Prenez contact\n          <\/a>\n        <\/div>\n      <\/div>\n    \n    <div class=\"o-flex__item u-1\/2@tablet\">\n      <record-explorer\n        endpoint='employees'\n        fields='title,acf,link,type,id,status,_links,_embedded'\n        :include='[163]'\n        :labels='{\"name\":\"collaboratrices et collaborateurs\",\"singular_name\":\"Employee\",\"add_new\":\"Add New\",\"add_new_item\":\"Add New Employee\",\"edit_item\":\"Edit Employee\",\"new_item\":\"New Employee\",\"view_item\":\"View Employee\",\"view_items\":\"View Employees\",\"search_items\":\"Search Employees\",\"not_found\":\"No employees found.\",\"not_found_in_trash\":\"No employees found in trash.\",\"parent_item_colon\":\"Parent Employee:\",\"all_items\":\"All Employees\",\"archives\":\"Employee Archives\",\"attributes\":\"Employee Attributes\",\"insert_into_item\":\"Insert into employee\",\"uploaded_to_this_item\":\"Uploaded to this employee\",\"featured_image\":\"Featured image\",\"set_featured_image\":\"Set featured image\",\"remove_featured_image\":\"Remove featured image\",\"use_featured_image\":\"Use as featured image\",\"filter_items_list\":\"Filter employees list\",\"filter_by_date\":\"Filter by date\",\"items_list_navigation\":\"Employees list navigation\",\"items_list\":\"Employees list\",\"item_published\":\"Employee published.\",\"item_published_privately\":\"Employee published privately.\",\"item_reverted_to_draft\":\"Employee reverted to draft.\",\"item_trashed\":\"Post trashed.\",\"item_scheduled\":\"Employee scheduled.\",\"item_updated\":\"Employee updated.\",\"item_link\":\"Post Link\",\"item_link_description\":\"A link to a post.\",\"menu_name\":\"collaboratrices et collaborateurs\",\"name_admin_bar\":\"Employee\",\"template_name\":\"Single item: Employee\"}'\n        :show-filters='false'\n      >\n        <template #record=\"props\">\n          <employee\n            alignment='horizontal'\n            :employee='props.record'\n            class=\"u-1\/1\"\n            :show-phone=\"true\"\n            :show-email=\"false\"\n          ><\/employee>\n        <\/template>\n      <\/record-explorer>\n    <\/div>\n  <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Le Building Information Modeling, ou BIM, permet une planification en r\u00e9seau et collaborative de la construction. L\u2019architecte Filip Coso \u00e9voque son utilisation chez Burckhardt: <\/p>\n","protected":false},"author":4,"featured_media":3706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"categories":[3],"locations":[],"class_list":["post-11466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/posts\/11466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/comments?post=11466"}],"version-history":[{"count":2,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/posts\/11466\/revisions"}],"predecessor-version":[{"id":11730,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/posts\/11466\/revisions\/11730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/media\/3706"}],"wp:attachment":[{"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/media?parent=11466"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/tags?post=11466"},{"taxonomy":"category","embeddable":true,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/categories?post=11466"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/burckhardt.swiss\/fr\/wp-json\/wp\/v2\/locations?post=11466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}